{"id":5724,"date":"2021-09-20T15:18:56","date_gmt":"2021-09-20T22:18:56","guid":{"rendered":"https:\/\/www.ait-pro.com\/aitpro-blog\/?page_id=5724"},"modified":"2021-09-20T15:22:30","modified_gmt":"2021-09-20T22:22:30","slug":"website-headers-check","status":"publish","type":"page","link":"https:\/\/www.ait-pro.com\/aitpro-blog\/website-headers-check\/","title":{"rendered":"Website Headers Check"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":167,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"website-headers-check.php","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-5724","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Check website headers using GET or HEAD Requests. Displays the website header response.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.ait-pro.com\/aitpro-blog\/website-headers-check\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ait-pro.com\\\/aitpro-blog\\\/website-headers-check\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ait-pro.com\\\/aitpro-blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ait-pro.com\\\/aitpro-blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ait-pro.com\\\/aitpro-blog\\\/website-headers-check\\\/#listItem\",\"name\":\"Website Headers Check\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ait-pro.com\\\/aitpro-blog\\\/website-headers-check\\\/#listItem\",\"position\":2,\"name\":\"Website Headers Check\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ait-pro.com\\\/aitpro-blog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ait-pro.com\\\/aitpro-blog\\\/#organization\",\"name\":\"BulletProof Security Blog\",\"description\":\"BulletProof Security Blog\",\"url\":\"https:\\\/\\\/www.ait-pro.com\\\/aitpro-blog\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ait-pro.com\\\/aitpro-blog\\\/website-headers-check\\\/#webpage\",\"url\":\"https:\\\/\\\/www.ait-pro.com\\\/aitpro-blog\\\/website-headers-check\\\/\",\"name\":\"Website Headers Check - Check website headers using GET or HEAD Requests\",\"description\":\"Check website headers using GET or HEAD Requests. Displays the website header response.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ait-pro.com\\\/aitpro-blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ait-pro.com\\\/aitpro-blog\\\/website-headers-check\\\/#breadcrumblist\"},\"datePublished\":\"2021-09-20T15:18:56-07:00\",\"dateModified\":\"2021-09-20T15:22:30-07:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ait-pro.com\\\/aitpro-blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ait-pro.com\\\/aitpro-blog\\\/\",\"name\":\"BulletProof Security Blog\",\"description\":\"BulletProof Security Blog\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ait-pro.com\\\/aitpro-blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Website Headers Check - Check website headers using GET or HEAD Requests","description":"Check website headers using GET or HEAD Requests. Displays the website header response.","canonical_url":"https:\/\/www.ait-pro.com\/aitpro-blog\/website-headers-check\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.ait-pro.com\/aitpro-blog\/website-headers-check\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.ait-pro.com\/aitpro-blog#listItem","position":1,"name":"Home","item":"https:\/\/www.ait-pro.com\/aitpro-blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ait-pro.com\/aitpro-blog\/website-headers-check\/#listItem","name":"Website Headers Check"}},{"@type":"ListItem","@id":"https:\/\/www.ait-pro.com\/aitpro-blog\/website-headers-check\/#listItem","position":2,"name":"Website Headers Check","previousItem":{"@type":"ListItem","@id":"https:\/\/www.ait-pro.com\/aitpro-blog#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/www.ait-pro.com\/aitpro-blog\/#organization","name":"BulletProof Security Blog","description":"BulletProof Security Blog","url":"https:\/\/www.ait-pro.com\/aitpro-blog\/"},{"@type":"WebPage","@id":"https:\/\/www.ait-pro.com\/aitpro-blog\/website-headers-check\/#webpage","url":"https:\/\/www.ait-pro.com\/aitpro-blog\/website-headers-check\/","name":"Website Headers Check - Check website headers using GET or HEAD Requests","description":"Check website headers using GET or HEAD Requests. Displays the website header response.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.ait-pro.com\/aitpro-blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.ait-pro.com\/aitpro-blog\/website-headers-check\/#breadcrumblist"},"datePublished":"2021-09-20T15:18:56-07:00","dateModified":"2021-09-20T15:22:30-07:00"},{"@type":"WebSite","@id":"https:\/\/www.ait-pro.com\/aitpro-blog\/#website","url":"https:\/\/www.ait-pro.com\/aitpro-blog\/","name":"BulletProof Security Blog","description":"BulletProof Security Blog","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.ait-pro.com\/aitpro-blog\/#organization"}}]}},"aioseo_meta_data":{"post_id":"5724","title":"#post_title - Check website headers using GET or HEAD Requests","description":"Check website headers using GET or HEAD Requests. Displays the website header response.","keywords":[],"keyphrases":{"focus":[],"additional":[]},"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"aioseo-web-page-6362fc217ce8f","slug":"web-page","graphName":"WebPage","label":"Web Page","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"phone":"","email":"","fax":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-09-20 22:18:14","updated":"2022-11-02 23:24:17","primary_term":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ait-pro.com\/aitpro-blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWebsite Headers Check\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.ait-pro.com\/aitpro-blog"},{"label":"Website Headers Check","link":"https:\/\/www.ait-pro.com\/aitpro-blog\/website-headers-check\/"}],"_links":{"self":[{"href":"https:\/\/www.ait-pro.com\/aitpro-blog\/wp-json\/wp\/v2\/pages\/5724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ait-pro.com\/aitpro-blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ait-pro.com\/aitpro-blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ait-pro.com\/aitpro-blog\/wp-json\/wp\/v2\/users\/167"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ait-pro.com\/aitpro-blog\/wp-json\/wp\/v2\/comments?post=5724"}],"version-history":[{"count":1,"href":"https:\/\/www.ait-pro.com\/aitpro-blog\/wp-json\/wp\/v2\/pages\/5724\/revisions"}],"predecessor-version":[{"id":5725,"href":"https:\/\/www.ait-pro.com\/aitpro-blog\/wp-json\/wp\/v2\/pages\/5724\/revisions\/5725"}],"wp:attachment":[{"href":"https:\/\/www.ait-pro.com\/aitpro-blog\/wp-json\/wp\/v2\/media?parent=5724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}